{"id":830,"date":"2019-04-01T09:47:06","date_gmt":"2019-04-01T13:47:06","guid":{"rendered":"http:\/\/www.kevenarseneault.com\/?p=830"},"modified":"2019-09-08T19:19:21","modified_gmt":"2019-09-08T23:19:21","slug":"top-3-des-exercices-pour-abdominaux","status":"publish","type":"post","link":"https:\/\/www.kevenarseneault.com\/fr\/top-3-des-exercices-pour-abdominaux\/","title":{"rendered":"Top 3 des exercices pour abdominaux"},"content":{"rendered":"<p>Pour ma chronique du mois d&rsquo;avril dans le FD magazine (www.fdfitness.ca), je vous parle de 3 exercices que j&rsquo;appr\u00e9cie \u00e9norm\u00e9ment pour la stimulation des muscles abdominaux.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=Rm2W_xIyQvs\">Cliquez ici pour visionner la vid\u00e9o !<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour ma chronique du mois d&rsquo;avril dans le FD magazine (www.fdfitness.ca), je vous parle de 3 exercices que j&rsquo;appr\u00e9cie \u00e9norm\u00e9ment pour la stimulation des muscles abdominaux. Cliquez ici pour visionner la vid\u00e9o !<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/posts\/830"}],"collection":[{"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/comments?post=830"}],"version-history":[{"count":2,"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/posts\/830\/revisions"}],"predecessor-version":[{"id":858,"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/posts\/830\/revisions\/858"}],"wp:attachment":[{"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/media?parent=830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/categories?post=830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kevenarseneault.com\/fr\/wp-json\/wp\/v2\/tags?post=830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}